{"id":987483944,"date":"2024-03-03T14:14:15","date_gmt":"2024-03-03T13:14:15","guid":{"rendered":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/?post_type=product&#038;p=987483944"},"modified":"2025-09-26T19:26:47","modified_gmt":"2025-09-26T17:26:47","slug":"just-kissed-lip-cheek-stain-forever-peach","status":"publish","type":"product","link":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/produkt\/just-kissed-lip-cheek-stain-forever-peach\/","title":{"rendered":"Justed Kissed Lip &#038; Cheek Stain &#8211; Forever Peach"},"content":{"rendered":"<p>&#8220;Ready to Bloom\u201c \u2013 so verhei\u00dfungsvoll klingt der Name der neuen Kollektion von jane iredale. Mit ihr feiert die Marke nicht nur den Fr\u00fchling, sondern auch ihr 30-j\u00e4hriges Bestehen.<\/p>\n<p>Die Jubil\u00e4ums-Kollektion von jane iredale ist eine Hommage an 30 Jahre Einsatz der Marke f\u00fcr die nat\u00fcrliche Sch\u00f6nheit. Mit ihren frischen, femininen Farben, die durch Janes eigenen Garten inspiriert wurden, setzen die beliebten Lidschatten, Blushes und der Just Kissed Lip Stain in trendigen Apricot-T\u00f6nen herrliche Impulse zum Fr\u00fchlingsbeginn. jane iredale m\u00f6chte mit dieser Kollektion Begeisterung f\u00fcr die Zukunft des Skincare-Make-ups erzeugen, denn 30 Jahre sind erst der Anfang!<\/p>\n<p>Der vielseitige Stift f\u00fcr Lippen und Wangen nutzt ausschlie\u00dflich nat\u00fcrliche Inhaltsstoffe, um Ihren nat\u00fcrlichen Lippenteint zu unterstreichen. Trocknet nicht aus, ist lang anhaltend und passt sich mit seiner ausschlie\u00dflich nat\u00fcrlichen Farbe Ihrer Haut an. Mit einem unwiderstehlichen Farbton umschmeichelt er den Unterton Ihrer Haut. (Reagiert auf den PH-Wert der Haut.)<\/p>\n<p>Olivenbutter, Avocadobutter und der Wachs von Wildrosen beruhigen die Lippen und machen sie geschmeidig. Rosenbl\u00fctenwachs und Bienenwachs spenden N\u00e4hrstoffe und Feuchtigkeit.<\/p>\n<p><em>ACHTUNG: Die Inhaltsstoffe dieses Lip Plumpers reagieren mit dem individuellen ph-Wert der Haut auf den Lippen. Die Farbe kann sich dadurch ver\u00e4ndern und in Ihrer Intensit\u00e4t variieren.<\/em><\/p>\n<p>&nbsp;<\/p>\n<h5>Beschreibung:<\/h5>\n<ul>\n<li>Ein Lippen- und Wangenstift, der f\u00fcr eine langanhaltende, individuelle Farbe auf Lippen und Wangen sorgt.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h5>Wirkung:<\/h5>\n<ul>\n<li>Pflegt die Lippen<\/li>\n<li>Tr\u00e4gt hauchd\u00fcnne Farbe auf die Lippen auf<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h5 style=\"display: inline;\">Inhalt:<\/h5>\n<p style=\"display: inline;\">3g<\/p>\n<p>&nbsp;<\/p>\n<h5>Inhaltsstoffe:<\/h5>\n<p>Triisostearylcitrat, Olea Europaea (Olivenfrucht\u00f6l), Persea Gratissima (Avocado\u00f6l), Cucurbita Pepo (K\u00fcrbiskern\u00f6l, Cera Alba (Bienenwachs), Simmondsia Chinensis (Jojobakern\u00f6l), Punica Granatum (Granatapfelextrakt), Rubus Fruticosus (Brombeerfruchtextrakt), Vaccinium Angustifolium (Heidelbeerfruchtextrakt), Vaccinium Macrocarpon (Fruchtextrakt der Cranberry), Camellia Sinensis (Bl\u00e4tterextrakt des Wei\u00dfen Tees), Carthamus Tinctorius (Samen\u00f6l der F\u00e4rberdiestel), Rosa Damascena (Rosenbl\u00fctenwachs), Tocopherol, Ascorbylpalmitat, Zitronens\u00e4ure. [+\/- (Kann enthalten:) Red 21 (CI 45380) (Aka 223)].<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein get\u00f6nter vielseitiger Stift f\u00fcr Lippen und Wangen in verschiedenen Farbnuancen.<\/p>\n","protected":false},"featured_media":987484272,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<strong>Anwendungsgebiete: <\/strong>\r\n\r\nAls Gesichtspackung wird masque verwendet bei allen Hautarten zur Straffung und Versch\u00f6nerung des Hautbildes.\r\nZur kurfristigen Therapie bei d\u00fcnner, empfindlicher Haut mit oberfl\u00e4chlichen Entz\u00fcndungen.\r\n\r\n<strong>Wirkungsweise:<\/strong>\r\n\r\nMasque erh\u00f6ht mit Hilfe der Lipacide RH (Lipoaminos\u00e4uren) die F\u00e4higkeit der Epidermis, den zullul\u00e4ren Wassergehalt stabil zu halten. Die Haut wird sichtbar straffer und elastischer. Lipacide RH wirkt gleichzeitig vorbeugend gegen bakterielle Entz\u00fcndungen.\r\n\r\n<strong>Anwendung<\/strong>:\r\n\r\nQuantit\u00e4t und Art der Anwendung sind nach dem individuellen und aktuellen Zustand der Haut festzulegen.\r\n\r\n<strong>Gegenanzeigen:<\/strong>\r\n\r\nDas Produkt sollte bei bekannter Campher-Unvertr\u00e4glichkeit nicht angewendet werden.\r\n\r\n\u00a0","_et_gb_content_width":""},"product_brand":[474],"product_cat":[101,129,83,433,222,131,86,438],"product_tag":[175,124,413,173,134],"class_list":["post-987483944","product","type-product","status-publish","has-post-thumbnail","product_brand-jane-iredale","product_cat-aktuelle-kollektion","product_cat-mineralmakeup-gesicht","product_cat-jane-iredale","product_cat-just-kissed-lip-cheek-stain","product_cat-mu-lippen","product_cat-mineralmakeup-lippen","product_cat-make-up","product_cat-ready-to-bloom-kollektion","product_tag-blush","product_tag-lippen","product_tag-lippenstift","product_tag-make-up","product_tag-teint","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"booking_location":null,"booking_location_type":null,"booking_duration":null,"booking_duration_unit":null,"booking_buffer":null,"booking_cost":null,"booking_resources":null,"exclude_global_add_ons":[],"addons":[],"_links":{"self":[{"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/product\/987483944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/comments?post=987483944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/media\/987484272"}],"wp:attachment":[{"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/media?parent=987483944"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/product_brand?post=987483944"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/product_cat?post=987483944"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/product_tag?post=987483944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}