{"id":987486119,"date":"2024-07-26T18:04:11","date_gmt":"2024-07-26T16:04:11","guid":{"rendered":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/?post_type=product&#038;p=987486119"},"modified":"2026-07-13T20:14:35","modified_gmt":"2026-07-13T18:14:35","slug":"phase-2-intervall","status":"publish","type":"product","link":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/produkt\/phase-2-intervall\/","title":{"rendered":"Phase 2 Intervall"},"content":{"rendered":"<h5>Anwendungsgebiete:<\/h5>\n<p>Bei d\u00fcnner, trockener und sensibler Haut, bei St\u00f6rungen im Wasserhaushalt der Haut, sowie zur Intervalltherapie mit Phase 2 aktive regeneration.<\/p>\n<p>&nbsp;<\/p>\n<h5>Wirkungsweise:<\/h5>\n<p>Phase 2 intervall bindet \u00fcber l\u00e4ngere Zeit Fett und Feuchtigkeit in den \u00e4u\u00dferen Hautschichten. Die Wiederherstellung des Gleichgewichtes im Wasserhaushalt der Haut wird mit Hilfe des Mineralstoffkomplexes und Hyalurons\u00e4ure unterst\u00fctzt. Besonders effektiv ist Phase 2 intervall auch bei Verhornungsst\u00f6rungen und \u00dcberverhornung.<\/p>\n<p>&nbsp;<\/p>\n<h5>Anwendung:<\/h5>\n<p>Menge, Einwirkungszeit und H\u00e4ufigkeit der Anwendung ist nach dem individuellen und aktuellen Hautzustand festzulegen.<\/p>\n<p>&nbsp;<\/p>\n<h5>Gegenanzeigen:<\/h5>\n<p>Bei bekannter Unvertr\u00e4glichkeit von Avocado-\u00d6l sollte das Produkt nicht verwendet werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reichhaltige Gesichtpflege, mit Mineralien und Hyalurons\u00e4ure. Sorgt f\u00fcr ein Gleichgewicht im Wasserhaushalt der Haut.<br \/>\n(Nur im Tiegel mit Avocado\u00f6l)<\/p>\n<p>Intervall mit Squalan\u00f6l im Airless Spender finden Sie <strong><a href=\"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/produkt\/phase-2-intervall-squalan\/\">hier<\/a><\/strong>.<\/p>\n","protected":false},"featured_media":987486124,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<strong>Anwendungsgebiete:<\/strong>\r\n\r\nBei d\u00fcnner, trockener und sensibler Haut, bei St\u00f6rungen im Wasserhaushalt der Haut, sowie zur Intervalltherapie mit phase 2 aktive regeneration.\r\n\r\n\u00a0\r\n\r\n<strong>Wirkungsweise:<\/strong>\r\n\r\nphase 2 intervall bindet \u00fcber l\u00e4ngere Zeit Fett und Feuchtigkeit in den \u00e4u\u00dferen Hautschichten. Die Wiederherstellung des Gleichgewichtes im Wasserhaushalt der Haut wird mit Hilfe des Mineralstoffkomplexes und Hyalurons\u00e4ure unterst\u00fctzt. Besonders effektiv ist phase 2 intervall auch bei Verhornungsst\u00f6rungen und \u00dcberverhornung.\r\n\r\n\u00a0\r\n\r\n<strong>Anwendung:<\/strong>\r\n\r\nMenge, Einwirkungszeit und H\u00e4ufigkeit der Anwendung ist nach dem individuellen und aktuellen Hautzustand festzulegen.\r\n\r\n\u00a0\r\n\r\n<strong>Gegenanzeigen:<\/strong>\r\n\r\nBei bekannter Unvertr\u00e4glichkeit von Avocado-\u00d6l sollte das Produkt nicht verwendet werden.\r\n\r\n<span style=\"font-weight: bold\">\u00a0<\/span>","_et_gb_content_width":""},"product_brand":[472],"product_cat":[372,84,210,214,85,90,43],"product_tag":[56,66,64,68,67],"class_list":["post-987486119","product","type-product","status-publish","has-post-thumbnail","product_brand-rosel-heim","product_cat-alle-rosel-heim-produkte","product_cat-gesicht","product_cat-gesichtspflege","product_cat-handpflege","product_cat-koerper","product_cat-rh-regeneration","product_cat-rosel-heim","product_tag-creme","product_tag-gesichtscreme","product_tag-hautschutz","product_tag-regeneration","product_tag-tagescreme","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"booking_location":null,"booking_location_type":null,"booking_duration":null,"booking_duration_unit":null,"booking_buffer":null,"booking_cost":null,"booking_resources":null,"exclude_global_add_ons":[],"addons":[],"_links":{"self":[{"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/product\/987486119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/comments?post=987486119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/media\/987486124"}],"wp:attachment":[{"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/media?parent=987486119"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/product_brand?post=987486119"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/product_cat?post=987486119"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.claresco-cosmetic.de\/kosmetik-shop\/wp-json\/wp\/v2\/product_tag?post=987486119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}